{"id":1497,"count":1,"description":"","link":"https:\/\/tekirdagboschservisi.com.tr\/index.php\/tag\/siemens-su-seviyesi-sensoru-arizasi\/","name":"Siemens su seviyesi sens\u00f6r\u00fc ar\u0131zas\u0131","slug":"siemens-su-seviyesi-sensoru-arizasi","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Siemens su seviyesi sens\u00f6r\u00fc ar\u0131zas\u0131 ar\u015fivleri - Tekirda\u011f Bosch Servisi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tekirdagboschservisi.com.tr\/index.php\/tag\/siemens-su-seviyesi-sensoru-arizasi\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Siemens su seviyesi sens\u00f6r\u00fc ar\u0131zas\u0131 ar\u015fivleri - Tekirda\u011f Bosch Servisi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tekirdagboschservisi.com.tr\/index.php\/tag\/siemens-su-seviyesi-sensoru-arizasi\/\" \/>\n<meta property=\"og:site_name\" content=\"Tekirda\u011f Bosch Servisi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/tekirdagboschservisi.com.tr\\\/index.php\\\/tag\\\/siemens-su-seviyesi-sensoru-arizasi\\\/\",\"url\":\"https:\\\/\\\/tekirdagboschservisi.com.tr\\\/index.php\\\/tag\\\/siemens-su-seviyesi-sensoru-arizasi\\\/\",\"name\":\"Siemens su seviyesi sens\u00f6r\u00fc ar\u0131zas\u0131 ar\u015fivleri - Tekirda\u011f Bosch Servisi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tekirdagboschservisi.com.tr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tekirdagboschservisi.com.tr\\\/index.php\\\/tag\\\/siemens-su-seviyesi-sensoru-arizasi\\\/#breadcrumb\"},\"inLanguage\":\"tr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tekirdagboschservisi.com.tr\\\/index.php\\\/tag\\\/siemens-su-seviyesi-sensoru-arizasi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/tekirdagboschservisi.com.tr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Siemens su seviyesi sens\u00f6r\u00fc ar\u0131zas\u0131\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tekirdagboschservisi.com.tr\\\/#website\",\"url\":\"https:\\\/\\\/tekirdagboschservisi.com.tr\\\/\",\"name\":\"Tekirda\u011f Bosch Servisi\",\"description\":\"0282 263 22 96\",\"publisher\":{\"@id\":\"https:\\\/\\\/tekirdagboschservisi.com.tr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tekirdagboschservisi.com.tr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tekirdagboschservisi.com.tr\\\/#organization\",\"name\":\"Tekirda\u011f Bosch Servisi\",\"url\":\"https:\\\/\\\/tekirdagboschservisi.com.tr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/tekirdagboschservisi.com.tr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tekirdagboschservisi.com.tr\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/7502c4fab3c11f90ed12b06b5e7b138d-1.jpg\",\"contentUrl\":\"https:\\\/\\\/tekirdagboschservisi.com.tr\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/7502c4fab3c11f90ed12b06b5e7b138d-1.jpg\",\"width\":250,\"height\":92,\"caption\":\"Tekirda\u011f Bosch Servisi\"},\"image\":{\"@id\":\"https:\\\/\\\/tekirdagboschservisi.com.tr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Siemens su seviyesi sens\u00f6r\u00fc ar\u0131zas\u0131 ar\u015fivleri - Tekirda\u011f Bosch Servisi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tekirdagboschservisi.com.tr\/index.php\/tag\/siemens-su-seviyesi-sensoru-arizasi\/","og_locale":"tr_TR","og_type":"article","og_title":"Siemens su seviyesi sens\u00f6r\u00fc ar\u0131zas\u0131 ar\u015fivleri - Tekirda\u011f Bosch Servisi","og_url":"https:\/\/tekirdagboschservisi.com.tr\/index.php\/tag\/siemens-su-seviyesi-sensoru-arizasi\/","og_site_name":"Tekirda\u011f Bosch Servisi","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/tekirdagboschservisi.com.tr\/index.php\/tag\/siemens-su-seviyesi-sensoru-arizasi\/","url":"https:\/\/tekirdagboschservisi.com.tr\/index.php\/tag\/siemens-su-seviyesi-sensoru-arizasi\/","name":"Siemens su seviyesi sens\u00f6r\u00fc ar\u0131zas\u0131 ar\u015fivleri - Tekirda\u011f Bosch Servisi","isPartOf":{"@id":"https:\/\/tekirdagboschservisi.com.tr\/#website"},"breadcrumb":{"@id":"https:\/\/tekirdagboschservisi.com.tr\/index.php\/tag\/siemens-su-seviyesi-sensoru-arizasi\/#breadcrumb"},"inLanguage":"tr"},{"@type":"BreadcrumbList","@id":"https:\/\/tekirdagboschservisi.com.tr\/index.php\/tag\/siemens-su-seviyesi-sensoru-arizasi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/tekirdagboschservisi.com.tr\/"},{"@type":"ListItem","position":2,"name":"Siemens su seviyesi sens\u00f6r\u00fc ar\u0131zas\u0131"}]},{"@type":"WebSite","@id":"https:\/\/tekirdagboschservisi.com.tr\/#website","url":"https:\/\/tekirdagboschservisi.com.tr\/","name":"Tekirda\u011f Bosch Servisi","description":"0282 263 22 96","publisher":{"@id":"https:\/\/tekirdagboschservisi.com.tr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tekirdagboschservisi.com.tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"},{"@type":"Organization","@id":"https:\/\/tekirdagboschservisi.com.tr\/#organization","name":"Tekirda\u011f Bosch Servisi","url":"https:\/\/tekirdagboschservisi.com.tr\/","logo":{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/tekirdagboschservisi.com.tr\/#\/schema\/logo\/image\/","url":"https:\/\/tekirdagboschservisi.com.tr\/wp-content\/uploads\/2024\/03\/7502c4fab3c11f90ed12b06b5e7b138d-1.jpg","contentUrl":"https:\/\/tekirdagboschservisi.com.tr\/wp-content\/uploads\/2024\/03\/7502c4fab3c11f90ed12b06b5e7b138d-1.jpg","width":250,"height":92,"caption":"Tekirda\u011f Bosch Servisi"},"image":{"@id":"https:\/\/tekirdagboschservisi.com.tr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/tekirdagboschservisi.com.tr\/index.php\/wp-json\/wp\/v2\/tags\/1497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tekirdagboschservisi.com.tr\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/tekirdagboschservisi.com.tr\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/tekirdagboschservisi.com.tr\/index.php\/wp-json\/wp\/v2\/posts?tags=1497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}